{"id":102640,"date":"2018-05-31T06:50:38","date_gmt":"2018-05-31T04:50:38","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=102640"},"modified":"2018-05-31T06:50:38","modified_gmt":"2018-05-31T04:50:38","slug":"netflix-spendiert-android-app-ueberarbeitetes-design","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/","title":{"rendered":"Netflix spendiert Android App \u00fcberarbeitetes Design"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-34416\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/11\/netflix-guthabenkarte.jpg\" alt=\"\" width=\"937\" height=\"606\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/11\/netflix-guthabenkarte.jpg 937w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/11\/netflix-guthabenkarte-150x97.jpg 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/11\/netflix-guthabenkarte-500x323.jpg 500w\" sizes=\"auto, (max-width: 937px) 100vw, 937px\" \/><\/p>\n<p>Wer Netflix auf seinem Android-Ger\u00e4t nutzt, dem wurde gestern ein neues Update bereitgestellt. Das Update mit der Versionsnummer 6.3.0 Build 27748 bringt diverse \u00c4nderungen am Design mit.<\/p>\n<p>Bislang befand sich die Navigstionsleiste samt Start-\/ Pause-Button und dem Button zum Zur\u00fcckspulen von 30 Sekunden am unteren Displayrand. Nun \u00e4ndert sich das ein oder andere. So wandern nun die Haupt-Steuerelemente in die Bildschirmmitte und werden deutlich gr\u00f6\u00dfer. Mittig liegt jetzt der Button f\u00fcr Start und Pause. Und links und rechts daneben gibt es endlich die lang ersehnten Buttons zum 10-Sekunden Vorspulen bzw. Zur\u00fcckspulen. Dieses kennen wir ja z.B. von Amazon Prime oder YouTube.<\/p>\n<p>Weiterhin neu ist auch, dass sich die Buttons f\u00fcr Sprache, Untertitel und Episodenauswahl am unteren Bildschirmrand unterhalb der Zeitleiste befinden. Vorher hat man diese oben Rechts gefunden. Zus\u00e4tzlich gesellt sich nun ein neuer Button mit der Bezeichnung &#8222;N\u00e4chste Folge&#8220; dazu. Dieser erm\u00f6glicht es, wie der Name schon sagt, direkt zur n\u00e4chsten Folge einer Serie zu springen.<\/p>\n<p>Mir gef\u00e4llt das umgestaltete Design. Hier nochmal der Changelog f\u00fcr die Android App von Netflix:<\/p>\n<ul>\n<li>Neue Schaltfl\u00e4chen zum Vor- und Zur\u00fcckspulen um 10 Sekunden erleichtern es Ihnen, genau an die Stelle zu kommen, die Sie sich anschauen wollen.<\/li>\n<li>Gr\u00f6\u00dfere Schaltfl\u00e4chen f\u00fcr z. B. Abspielen\/Anhalten und Schaltfl\u00e4chen mit Beschriftung, damit Sie schnell Folgen ausw\u00e4hlen oder Audio und Untertitel anschalten k\u00f6nnen.<\/li>\n<\/ul>\n<!-- WP-Appbox (Version: 4.5.13 \/\/ Store: googleplay \/\/ ID: com.netflix.mediaclient) -->\n<div class=\"wpappbox wpappbox-5bffa2644f3b4ba96bb7d2c3bba20c95 googleplay deprecated simple\">\n\t<div class=\"qrcode\"><img decoding=\"async\" src=\"https:\/\/api.qrserver.com\/v1\/create-qr-code\/?data=https%3A%2F%2Fplay.google.com%2Fstore%2Fapps%2Fdetails%3Fid%3Dcom.netflix.mediaclient%26hl%3Dde&size=200x200&ecc=M&margin=0\" alt=\"Netflix\" \/><\/div>\n\t<div class=\"appicon\">\n\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.netflix.mediaclient&hl=de\" aria-label=\"Netflix\"><img decoding=\"async\" src=\"\/\/lh3.googleusercontent.com\/jcbqFma-5e91cY9MlEasA-fvCRJK493MxphrqbBd8oS74FtYg00IXeOAn0ahsLprxIA=w128\" alt=\"Netflix\" \/><\/a>\n\t<\/div>\n\t<div class=\"applinks\">\n\t\t<div class=\"appbuttons\">\n\t\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.netflix.mediaclient&hl=de\" aria-label=\"Netflix\">Download<\/a>\n\t\t\t<span onMouseOver=\"jQuery('.wpappbox-5bffa2644f3b4ba96bb7d2c3bba20c95 .qrcode').show();\" onMouseOut=\"jQuery('.wpappbox-5bffa2644f3b4ba96bb7d2c3bba20c95 .qrcode').hide();\">QR-Code<\/span>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"appdetails\">\n\t\t<div class=\"apptitle\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.netflix.mediaclient&hl=de\" title=\"Netflix\" aria-label=\"Netflix\" class=\"apptitle\">Netflix<\/a><\/div>\n\t\t<div class=\"developer\">\n\t\t\t<span class=\"label\">Entwickler: <\/span>\n\t\t\t<span class=\"value\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/play.google.com\/store\/apps\/developer?id=Netflix,+Inc.\">Netflix, Inc.<\/a><\/span>\n\t\t<\/div>\n\t\t<div class=\"price\">\n\t\t\t<span class=\"label\">Preis: <\/span>\n\t\t\t<span class=\"value\">Kostenlos<sup>+<\/sup><\/span> \n\t\t\t<span class=\"rating\"><div title=\"4 von 5 Sternen\" class=\"rating-stars stars-monochrome stars40\"><\/div><\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div><!-- \/WP-Appbox -->\n","protected":false},"excerpt":{"rendered":"<p>Wer Netflix auf seinem Android-Ger\u00e4t nutzt, dem wurde gestern ein neues Update bereitgestellt. Das Update mit der Versionsnummer 6.3.0 Build 27748 bringt diverse \u00c4nderungen am Design mit. Bislang befand sich die Navigstionsleiste samt Start-\/ Pause-Button und dem Button zum Zur\u00fcckspulen&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":67318,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,894,152],"tags":[31423],"class_list":["post-102640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-android","category-software","tag-netflix-app-android"],"wp_featured_image":{"id":67318,"alt_text":"","description":"","media_type":"image","media_details":{"width":1440,"height":1182,"file":"2016\/06\/Netflix_Neues_Logo-1.png","sizes":{"thumbnail":{"file":"Netflix_Neues_Logo-1-250x205.png","width":250,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1-250x205.png"},"medium":{"file":"Netflix_Neues_Logo-1-439x360.png","width":439,"height":360,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1-439x360.png"},"large":{"file":"Netflix_Neues_Logo-1-710x583.png","width":710,"height":583,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1-710x583.png"},"wp_review_large":{"file":"Netflix_Neues_Logo-1-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1-320x200.png"},"wp_review_small":{"file":"Netflix_Neues_Logo-1-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1-65x65.png"},"blog-large":{"file":"Netflix_Neues_Logo-1-642x300.png","width":642,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1-642x300.png"},"blog-medium":{"file":"Netflix_Neues_Logo-1-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1-306x205.png"},"recent-thumb":{"file":"Netflix_Neues_Logo-1-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1-350x316.png"},"service-featured":{"file":"Netflix_Neues_Logo-1-600x330.png","width":600,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1-600x330.png"},"wp_rp_thumbnail":{"file":"Netflix_Neues_Logo-1-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1-150x150.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":68869,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1.png"},"commentcount":1,"wp_comments":[{"id":74401,"parent":0,"author":0,"author_name":"Daniel","author_email":"sth.daniel@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7be1f9dba36c1de76cbe24eb4fb45948830de12f40e73042e461e386a9534383?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7be1f9dba36c1de76cbe24eb4fb45948830de12f40e73042e461e386a9534383?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7be1f9dba36c1de76cbe24eb4fb45948830de12f40e73042e461e386a9534383?s=96&d=mm&r=g"},"date":"2018-05-31T16:46:59","cld_nonce":"82f011626f","content":{"rendered":"<p>Hoffe wir mal das auch bald die Win10 App angepasst wird. ^^<\/p>\n"},"status":"1"}],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Netflix spendiert Android App \u00fcberarbeitetes Design - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Netflix spendiert Android App \u00fcberarbeitetes Design\" \/>\n<meta property=\"og:description\" content=\"Wer Netflix auf seinem Android-Ger\u00e4t nutzt, dem wurde gestern ein neues Update bereitgestellt. Das Update mit der Versionsnummer 6.3.0 Build 27748 bringt diverse \u00c4nderungen am Design mit. Bislang befand sich die Navigstionsleiste samt Start-\/ Pause-Button und dem Button zum Zur\u00fcckspulen&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-31T04:50:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1182\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/31\\\/netflix-spendiert-android-app-ueberarbeitetes-design\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/31\\\/netflix-spendiert-android-app-ueberarbeitetes-design\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Netflix spendiert Android App \u00fcberarbeitetes Design\",\"datePublished\":\"2018-05-31T04:50:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/31\\\/netflix-spendiert-android-app-ueberarbeitetes-design\\\/\"},\"wordCount\":245,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/31\\\/netflix-spendiert-android-app-ueberarbeitetes-design\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Netflix_Neues_Logo-1.png\",\"keywords\":[\"Netflix App Android\"],\"articleSection\":{\"1\":\"Android\",\"2\":\"Software &amp; Updates\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/31\\\/netflix-spendiert-android-app-ueberarbeitetes-design\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/31\\\/netflix-spendiert-android-app-ueberarbeitetes-design\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/31\\\/netflix-spendiert-android-app-ueberarbeitetes-design\\\/\",\"name\":\"Netflix spendiert Android App \u00fcberarbeitetes Design - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/31\\\/netflix-spendiert-android-app-ueberarbeitetes-design\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/31\\\/netflix-spendiert-android-app-ueberarbeitetes-design\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Netflix_Neues_Logo-1.png\",\"datePublished\":\"2018-05-31T04:50:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/31\\\/netflix-spendiert-android-app-ueberarbeitetes-design\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/31\\\/netflix-spendiert-android-app-ueberarbeitetes-design\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/31\\\/netflix-spendiert-android-app-ueberarbeitetes-design\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Netflix_Neues_Logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Netflix_Neues_Logo-1.png\",\"width\":1440,\"height\":1182},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/31\\\/netflix-spendiert-android-app-ueberarbeitetes-design\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Netflix spendiert Android App \u00fcberarbeitetes Design\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Netflix spendiert Android App \u00fcberarbeitetes Design - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/","og_locale":"de_DE","og_type":"article","og_title":"Netflix spendiert Android App \u00fcberarbeitetes Design","og_description":"Wer Netflix auf seinem Android-Ger\u00e4t nutzt, dem wurde gestern ein neues Update bereitgestellt. Das Update mit der Versionsnummer 6.3.0 Build 27748 bringt diverse \u00c4nderungen am Design mit. Bislang befand sich die Navigstionsleiste samt Start-\/ Pause-Button und dem Button zum Zur\u00fcckspulen&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-05-31T04:50:38+00:00","og_image":[{"width":1440,"height":1182,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1.png","type":"image\/png"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Netflix spendiert Android App \u00fcberarbeitetes Design","datePublished":"2018-05-31T04:50:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/"},"wordCount":245,"commentCount":1,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1.png","keywords":["Netflix App Android"],"articleSection":{"1":"Android","2":"Software &amp; Updates"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/","name":"Netflix spendiert Android App \u00fcberarbeitetes Design - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1.png","datePublished":"2018-05-31T04:50:38+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1.png","width":1440,"height":1182},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/31\/netflix-spendiert-android-app-ueberarbeitetes-design\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Netflix spendiert Android App \u00fcberarbeitetes Design"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/06\/Netflix_Neues_Logo-1.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/102640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=102640"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/102640\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/67318"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=102640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=102640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=102640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}