{"id":101252,"date":"2018-05-03T05:57:07","date_gmt":"2018-05-03T03:57:07","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=101252"},"modified":"2018-05-03T05:58:42","modified_gmt":"2018-05-03T03:58:42","slug":"lg-g7-thinq-offiziell-vorgestellt","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/","title":{"rendered":"LG G7 ThinQ offiziell vorgestellt"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-101254\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02.jpg\" alt=\"\" width=\"6592\" height=\"9058\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02.jpg 6592w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02-149x205.jpg 149w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02-262x360.jpg 262w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02-424x583.jpg 424w\" sizes=\"auto, (max-width: 6592px) 100vw, 6592px\" \/><\/p>\n<p>Wie angek\u00fcndigt, hat LG gestern sein neues LG G7 ThinQ der \u00d6ffentlichkeit pr\u00e4sentiert und somit f\u00fcr 2018 sein erstes wirklich neues Smartphone-Flaggschiff vorgestellt. Dieses m\u00f6chte dank super hellem Display und Boombox Lautsprechern die User vom Kauf \u00fcberzeugen.<\/p>\n<p>Leicht wird es f\u00fcr LG aufgrund der starken Konkurrenz wieder nicht werden. Technisch ist das G7 sehr gut ausgestattet. Neben dem Snapdragon 845 und 4 GB RAM ist ein Display mit QHD+ Aufl\u00f6sung verbaut worden. Weiterhin gibt&#8217;s eine zus\u00e4tzliche Taste an der Geh\u00e4useseite zum Aufrufen des Google Assistant.<\/p>\n<p>Im Folgenden einmal die technischen Daten vom LG G7 ThinQ in der \u00dcbersicht:<\/p>\n<ul>\n<li>Prozessor: Qualcomm Snapdragon 845 Mobile Plattform<\/li>\n<li>Bildschirm: Extra helles 6.1\u201c FullVision Display QHD+ Aufl\u00f6sung (3120 x 1440\/564 ppi) und 19,5:9 Seitenverh\u00e4ltnis<\/li>\n<li>Speicher: 4GB LPDDR4x RAM \/ 64GB UFS 2.1 ROM \/ MicroSD (bis zu 2TB)<\/li>\n<li>Dual-Hauptkamera: 16MP Dual-Hauptkamera mit verbesserten Weitwinkel (F1,9 \/ 107\u00b0) \/ 16MP Standardwinkel (F1,6 \/ 71\u00b0)<\/li>\n<li>Selfie-Kamera: 8MP (F1,9 \/ 80\u00b0)<\/li>\n<li>Akku: 3000mAh<\/li>\n<li>Betriebssystem: Android 8.0 Oreo<\/li>\n<li>Abmessungen: 153,2 x 71,9 x 7,9mm<\/li>\n<li>Gewicht: 162g<\/li>\n<li>Verbindungstechnolgien: Wi-Fi 802.11 a, b, g, n, ac \/ Bluetooth 5.0 BLE \/ NFC \/ USB Typ-C 2.0 (3.1 kompatibel)<\/li>\n<li>Farben: New Platinum Gray \/ New Aurora Black<\/li>\n<li>Weitere Leistungsmerkmale: Extra helles Display \/ AI Cam \/ Extra helle Kamera \/ Google Lens \/ AI Haptic \/ Google Assistant-Taste\/ Spracherkennung bei weiter Entfernung \/ Boombox-Lautsprecher\/ HiFi Quad DAC \/ DTS:X 3D Surround Sound \/ Wasser- und staubgesch\u00fctzt nach IP68 \/ sto\u00dfsicher gem\u00e4\u00df MIL-STD 810G \/ HDR10 \/ Gesichtserkennung \/ Fingerabdrucksensor \/ Qualcomm Quick Charge 3.0 Technologie \/ Wireless Charging \/ FM Radio<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-101253\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-01.jpg\" alt=\"\" width=\"6092\" height=\"8190\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-01.jpg 6092w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-01-152x205.jpg 152w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-01-268x360.jpg 268w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-01-434x583.jpg 434w\" sizes=\"auto, (max-width: 6092px) 100vw, 6092px\" \/><\/p>\n<p>Gerade in Sachen Kamera wird das LG G7 ThinQ wohl nicht einem Huawei P20 Pro das Wasser reichen k\u00f6nnen und ob man sich gegen ein Samsung Galaxy S9 (+) durchsetzen kann, bleibt abzuwarten. Rein optisch gef\u00e4llt es mir aber gut. In Deutschland wird das LG G7 ThinQ ab Anfang Juni in den Farben \u201eNew Aurora Black\u201c und \u201eNew Platinum Gray\u201c zu einem UVP von 849,- Euro erh\u00e4ltlich sein. Pre-Orders sind ab 25. Mai m\u00f6glich.<\/p>\n<p>Wer noch mehr Details zum LG G7 ThinQ wissen m\u00f6chte, findet diese in der <a href=\"http:\/\/presse.lge.de\/2018\/05\/02\/lg-g7-thinq-bietet-integration-von-kuenstlicher-intelligenz-ai-fuer-maximalen-bedienkomfort\/\" target=\"_blank\" rel=\"noopener\">Pressemitteilung von LG<\/a>.<\/p>\n<div class=\"video-container\"><div style=\"position:relative;width:100%;max-width:810px;height:456px;background-color:black;color:white;padding:0px;\" data-video-id=\"ybG8iWK4e2I\">\n\t\t\t\t\t\t<div style=\"text-align: center;\">\n\t\t\t\t\t\t\t<span class=\"hint-text\">Erst durch Klick auf den Button werden Daten an Youtube \u00fcbermittelt und dir das Video angezeigt.<br\/>Mehr dazu in unserer <a href=\"https:\/\/www.deskmodder.de\/blog\/datenschutz-auf-deskmodder-de\/\" target=\"_blank\">Datenschutzrichtlinie<\/a><\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div style=\"text-align: center; margin-top: 10px;\">\n\t\t\t\t\t\t\t<button onclick=\"showVideo(this)\">Verstanden!<\/button>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"video-container\" style=\"display:none;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/ybG8iWK4e2I\/hqdefault.jpg\" alt=\"Vorschaubild\" style=\"width:100%; max-width:810px;\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script>\n\t\t\t\t\t\tfunction showVideo(button) {\n\t\t\t\t\t\t\tconst videoID = button.parentElement.parentElement.getAttribute(\"data-video-id\");\n\t\t\t\t\t\t\tconsole.log(\"Video ID:\", videoID); \/\/ Debugging\n\t\t\t\t\t\t\tconst iframeHTML = \"<iframe width='810' height='456' src='https:\/\/www.youtube-nocookie.com\/embed\/\" + videoID + \"?feature=oembed' frameborder='0' allow='accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture' allowfullscreen><\/iframe>\";\n\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".video-container\").innerHTML = iframeHTML;\n\n\t\t\t\t\t\t\t\/\/ Video-Container sichtbar machen\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".video-container\").style.display = \"block\";\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".hint-text\").style.display = \"none\";\n\t\t\t\t\t\t\tbutton.remove();\n\t\t\t\t\t\t}\n\t\t\t\t\t<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Wie angek\u00fcndigt, hat LG gestern sein neues LG G7 ThinQ der \u00d6ffentlichkeit pr\u00e4sentiert und somit f\u00fcr 2018 sein erstes wirklich neues Smartphone-Flaggschiff vorgestellt. Dieses m\u00f6chte dank super hellem Display und Boombox Lautsprechern die User vom Kauf \u00fcberzeugen. Leicht wird es&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":101254,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286],"tags":[34323],"class_list":["post-101252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","tag-lg-g7-thinq"],"wp_featured_image":{"id":101254,"alt_text":"","description":"","media_type":"image","media_details":{"width":6592,"height":9058,"file":"2018\/05\/bild-lg-g7-thinq-02.jpg","sizes":{"thumbnail":{"file":"bild-lg-g7-thinq-02-149x205.jpg","width":149,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02-149x205.jpg"},"medium":{"file":"bild-lg-g7-thinq-02-262x360.jpg","width":262,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02-262x360.jpg"},"large":{"file":"bild-lg-g7-thinq-02-424x583.jpg","width":424,"height":583,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02-424x583.jpg"},"wp_review_large":{"file":"bild-lg-g7-thinq-02-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02-320x200.jpg"},"wp_review_small":{"file":"bild-lg-g7-thinq-02-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02-65x65.jpg"},"blog-large":{"file":"bild-lg-g7-thinq-02-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02-642x300.jpg"},"blog-medium":{"file":"bild-lg-g7-thinq-02-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02-306x205.jpg"},"recent-thumb":{"file":"bild-lg-g7-thinq-02-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02-350x316.jpg"},"service-featured":{"file":"bild-lg-g7-thinq-02-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02-600x330.jpg"},"wp_rp_thumbnail":{"file":"bild-lg-g7-thinq-02-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":101252,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02.jpg"},"commentcount":2,"wp_comments":[{"id":72290,"parent":0,"author":0,"author_name":"7four7","author_email":"gerhardsu@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d8bfad632b37fcdfe497d08f58d6ff9f37069e3e4151861ec52439c610cbc6de?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d8bfad632b37fcdfe497d08f58d6ff9f37069e3e4151861ec52439c610cbc6de?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d8bfad632b37fcdfe497d08f58d6ff9f37069e3e4151861ec52439c610cbc6de?s=96&d=mm&r=g"},"date":"2018-05-03T07:06:47","cld_nonce":"82f011626f","content":{"rendered":"<p>F\u00fcr 849 Euro mit der Frage, kann es dem und dem das Wasser reichen &#8230; auch Nokia legt dieses eigenartige Selbstbewu\u00dftsein mit dem N8 Sirocco f\u00fcr 749 Euro an den Tag. Schaut man wo der Preis f\u00fcr das Huawei u. Samsung schon jetzt gelandet ist dann wirft sich LG und auch Nokia schon jetzt aus dem Rennen und das f\u00fchrt dazu das man auch den Anschlu\u00df im HighEnd g\u00e4nzlich verliert.<\/p>\n"},"status":"1"},{"id":72291,"parent":0,"author":0,"author_name":"Homi","author_email":"homi@msn.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/38af72adc101db547edf74af6ea7930a9075871b8d94351efd1e3d7ff353532f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/38af72adc101db547edf74af6ea7930a9075871b8d94351efd1e3d7ff353532f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/38af72adc101db547edf74af6ea7930a9075871b8d94351efd1e3d7ff353532f?s=96&d=mm&r=g"},"date":"2018-05-03T07:50:03","cld_nonce":"82f011626f","content":{"rendered":"<p>Einfach ein paar Wochen warten, also wer Interesse hat. LG Smartis fallen doch nach acht bis zehn Wochen um 200 &#8211; 300 Euro im Preis zur UVP, im August sollte es das G7 dann f\u00fcr um die 550 &#8211; 600 Euro geben. Muss ja auch, die Konkurrenz f\u00e4llt ja auch schon Preis. Ich finde das G7 sehr interessant, mal schauen, was das OnePlus 6 preislich so sagt, zwischen G7 und OP6 werde ich mich dann entscheiden und das beerbt dann mein derzeitiges OP3T, das als Backup in die Schublade wandert. Aber evtl. wird es ja auch ein LG V30, das es bald f\u00fcr weit unter 500 gibt, mit Google Cam Mod macht das n\u00e4mlich auch vorz\u00fcgliche Bilder, wie das OP3T auch.<\/p>\n"},"status":"1"}],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>LG G7 ThinQ offiziell vorgestellt - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LG G7 ThinQ offiziell vorgestellt\" \/>\n<meta property=\"og:description\" content=\"Wie angek\u00fcndigt, hat LG gestern sein neues LG G7 ThinQ der \u00d6ffentlichkeit pr\u00e4sentiert und somit f\u00fcr 2018 sein erstes wirklich neues Smartphone-Flaggschiff vorgestellt. Dieses m\u00f6chte dank super hellem Display und Boombox Lautsprechern die User vom Kauf \u00fcberzeugen. Leicht wird es&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-03T03:57:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-03T03:58:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"6592\" \/>\n\t<meta property=\"og:image:height\" content=\"9058\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/03\\\/lg-g7-thinq-offiziell-vorgestellt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/03\\\/lg-g7-thinq-offiziell-vorgestellt\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"LG G7 ThinQ offiziell vorgestellt\",\"datePublished\":\"2018-05-03T03:57:07+00:00\",\"dateModified\":\"2018-05-03T03:58:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/03\\\/lg-g7-thinq-offiziell-vorgestellt\\\/\"},\"wordCount\":335,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/03\\\/lg-g7-thinq-offiziell-vorgestellt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/bild-lg-g7-thinq-02.jpg\",\"keywords\":[\"LG G7 ThinQ\"],\"articleSection\":{\"1\":\"Hardware\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/03\\\/lg-g7-thinq-offiziell-vorgestellt\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/03\\\/lg-g7-thinq-offiziell-vorgestellt\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/03\\\/lg-g7-thinq-offiziell-vorgestellt\\\/\",\"name\":\"LG G7 ThinQ offiziell vorgestellt - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/03\\\/lg-g7-thinq-offiziell-vorgestellt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/03\\\/lg-g7-thinq-offiziell-vorgestellt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/bild-lg-g7-thinq-02.jpg\",\"datePublished\":\"2018-05-03T03:57:07+00:00\",\"dateModified\":\"2018-05-03T03:58:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/03\\\/lg-g7-thinq-offiziell-vorgestellt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/03\\\/lg-g7-thinq-offiziell-vorgestellt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/03\\\/lg-g7-thinq-offiziell-vorgestellt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/bild-lg-g7-thinq-02.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/bild-lg-g7-thinq-02.jpg\",\"width\":6592,\"height\":9058},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/05\\\/03\\\/lg-g7-thinq-offiziell-vorgestellt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LG G7 ThinQ offiziell vorgestellt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"LG G7 ThinQ offiziell vorgestellt - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/","og_locale":"de_DE","og_type":"article","og_title":"LG G7 ThinQ offiziell vorgestellt","og_description":"Wie angek\u00fcndigt, hat LG gestern sein neues LG G7 ThinQ der \u00d6ffentlichkeit pr\u00e4sentiert und somit f\u00fcr 2018 sein erstes wirklich neues Smartphone-Flaggschiff vorgestellt. Dieses m\u00f6chte dank super hellem Display und Boombox Lautsprechern die User vom Kauf \u00fcberzeugen. Leicht wird es&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-05-03T03:57:07+00:00","article_modified_time":"2018-05-03T03:58:42+00:00","og_image":[{"width":6592,"height":9058,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"LG G7 ThinQ offiziell vorgestellt","datePublished":"2018-05-03T03:57:07+00:00","dateModified":"2018-05-03T03:58:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/"},"wordCount":335,"commentCount":2,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02.jpg","keywords":["LG G7 ThinQ"],"articleSection":{"1":"Hardware"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/","name":"LG G7 ThinQ offiziell vorgestellt - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02.jpg","datePublished":"2018-05-03T03:57:07+00:00","dateModified":"2018-05-03T03:58:42+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02.jpg","width":6592,"height":9058},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/05\/03\/lg-g7-thinq-offiziell-vorgestellt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"LG G7 ThinQ offiziell vorgestellt"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/bild-lg-g7-thinq-02.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/101252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=101252"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/101252\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/101254"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=101252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=101252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=101252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}