{"id":100815,"date":"2018-04-25T05:16:39","date_gmt":"2018-04-25T03:16:39","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=100815"},"modified":"2018-04-25T05:16:39","modified_gmt":"2018-04-25T03:16:39","slug":"fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/","title":{"rendered":"FRITZ!Wlan USB Stick AC 430\u00a0 MU-MIMO erh\u00e4lt Update gegen KRACK-Sicherheitsl\u00fccke"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-81679\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/avm-fritzwlan-stick-ac-430-mu-mimo-freigestellt.png\" alt=\"\" width=\"1920\" height=\"1080\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/avm-fritzwlan-stick-ac-430-mu-mimo-freigestellt.png 1920w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/avm-fritzwlan-stick-ac-430-mu-mimo-freigestellt-306x172.png 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/avm-fritzwlan-stick-ac-430-mu-mimo-freigestellt-500x281.png 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/avm-fritzwlan-stick-ac-430-mu-mimo-freigestellt-810x456.png 810w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p>Kurzinfo f\u00fcr die Nutzer eines FRITZ!Wlan USB Stick AC 430 MU-MIMO. AVM hat ein kleines aber wichtiges Update bereitgestellt.<\/p>\n<p>Die nun verf\u00fcgbare Version 6.20.10 soll die KRACK &#8211; Sicherheitsl\u00fccke schlie\u00dfen. Mehr gibt der Changelog auch nicht her.<\/p>\n<ul>\n<li>Fix gegen Key Reinstallation Attack (KRACK)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Kurzinfo f\u00fcr die Nutzer eines FRITZ!Wlan USB Stick AC 430 MU-MIMO. AVM hat ein kleines aber wichtiges Update bereitgestellt. Die nun verf\u00fcgbare Version 6.20.10 soll die KRACK &#8211; Sicherheitsl\u00fccke schlie\u00dfen. Mehr gibt der Changelog auch nicht her. Fix gegen Key&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":71360,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286,152],"tags":[2543,35740],"class_list":["post-100815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","category-software","tag-avm","tag-fritzwlan-usb-stick-ac-430-mu-mimo"],"wp_featured_image":{"id":71360,"alt_text":"","description":"","media_type":"image","media_details":{"width":1920,"height":1080,"file":"2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt.png","sizes":{"thumbnail":{"file":"AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-306x172.png","width":306,"height":172,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-306x172.png"},"medium":{"file":"AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-500x281.png","width":500,"height":281,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-500x281.png"},"large":{"file":"AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-810x456.png","width":810,"height":456,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-810x456.png"},"wp_review_large":{"file":"AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-320x200.png"},"wp_review_small":{"file":"AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-65x65.png"},"blog-large":{"file":"AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-642x300.png","width":642,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-642x300.png"},"blog-medium":{"file":"AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-306x205.png"},"recent-thumb":{"file":"AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-350x316.png"},"service-featured":{"file":"AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-600x330.png","width":600,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-600x330.png"},"wp_rp_thumbnail":{"file":"AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt-150x150.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":71347,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt.png"},"commentcount":0,"wp_comments":[],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>FRITZ!Wlan USB Stick AC 430\u00a0 MU-MIMO erh\u00e4lt Update gegen KRACK-Sicherheitsl\u00fccke - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FRITZ!Wlan USB Stick AC 430\u00a0 MU-MIMO erh\u00e4lt Update gegen KRACK-Sicherheitsl\u00fccke\" \/>\n<meta property=\"og:description\" content=\"Kurzinfo f\u00fcr die Nutzer eines FRITZ!Wlan USB Stick AC 430 MU-MIMO. AVM hat ein kleines aber wichtiges Update bereitgestellt. Die nun verf\u00fcgbare Version 6.20.10 soll die KRACK &#8211; Sicherheitsl\u00fccke schlie\u00dfen. Mehr gibt der Changelog auch nicht her. Fix gegen Key&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-25T03:16:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/25\\\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/25\\\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"FRITZ!Wlan USB Stick AC 430\u00a0 MU-MIMO erh\u00e4lt Update gegen KRACK-Sicherheitsl\u00fccke\",\"datePublished\":\"2018-04-25T03:16:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/25\\\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\\\/\"},\"wordCount\":58,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/25\\\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt.png\",\"keywords\":[\"AVM\",\"FRITZ!Wlan USB Stick AC 430\u00a0 MU-MIMO\"],\"articleSection\":{\"1\":\"Hardware\",\"2\":\"Software &amp; Updates\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/25\\\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/25\\\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/25\\\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\\\/\",\"name\":\"FRITZ!Wlan USB Stick AC 430\u00a0 MU-MIMO erh\u00e4lt Update gegen KRACK-Sicherheitsl\u00fccke - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/25\\\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/25\\\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt.png\",\"datePublished\":\"2018-04-25T03:16:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/25\\\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/25\\\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/25\\\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/25\\\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FRITZ!Wlan USB Stick AC 430\u00a0 MU-MIMO erh\u00e4lt Update gegen KRACK-Sicherheitsl\u00fccke\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FRITZ!Wlan USB Stick AC 430\u00a0 MU-MIMO erh\u00e4lt Update gegen KRACK-Sicherheitsl\u00fccke - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/","og_locale":"de_DE","og_type":"article","og_title":"FRITZ!Wlan USB Stick AC 430\u00a0 MU-MIMO erh\u00e4lt Update gegen KRACK-Sicherheitsl\u00fccke","og_description":"Kurzinfo f\u00fcr die Nutzer eines FRITZ!Wlan USB Stick AC 430 MU-MIMO. AVM hat ein kleines aber wichtiges Update bereitgestellt. Die nun verf\u00fcgbare Version 6.20.10 soll die KRACK &#8211; Sicherheitsl\u00fccke schlie\u00dfen. Mehr gibt der Changelog auch nicht her. Fix gegen Key&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-04-25T03:16:39+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt.png","type":"image\/png"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"FRITZ!Wlan USB Stick AC 430\u00a0 MU-MIMO erh\u00e4lt Update gegen KRACK-Sicherheitsl\u00fccke","datePublished":"2018-04-25T03:16:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/"},"wordCount":58,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt.png","keywords":["AVM","FRITZ!Wlan USB Stick AC 430\u00a0 MU-MIMO"],"articleSection":{"1":"Hardware","2":"Software &amp; Updates"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/","name":"FRITZ!Wlan USB Stick AC 430\u00a0 MU-MIMO erh\u00e4lt Update gegen KRACK-Sicherheitsl\u00fccke - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt.png","datePublished":"2018-04-25T03:16:39+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/25\/fritzwlan-usb-stick-ac-430-mu-mimo-erhaelt-update-gegen-krack-sicherheitsluecke\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"FRITZ!Wlan USB Stick AC 430\u00a0 MU-MIMO erh\u00e4lt Update gegen KRACK-Sicherheitsl\u00fccke"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/AVM_FRITZWLAN_Stick_AC_430_MU-MIMO_freigestellt.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/100815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=100815"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/100815\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/71360"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=100815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=100815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=100815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}