{"id":1004,"date":"2011-10-17T16:34:46","date_gmt":"2011-10-17T14:34:46","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=1004"},"modified":"2023-01-14T17:16:20","modified_gmt":"2023-01-14T16:16:20","slug":"xwidget-anzeigen-auf-dem-desktop","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/","title":{"rendered":"XWidget Anzeigen auf dem Desktop"},"content":{"rendered":"<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-22-2.jpg\" rel=\"lightbox[1004]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-1005\" title=\"1-22-2\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-22-2-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0Ihr m\u00f6gt \u00a0Anzeigen auf dem Desktop mit Samurize oder Rainmeter? Dann ist XWidget vielleicht auch etwas f\u00fcr euch. \u00a0 XWidget ist f\u00fcr XP, Vista, Windows 7 und auch Windows 8.<\/p>\n<p>Auf den ersten Blick sind die Widgets wie wir sie von Vista her kennen. Aber die XWidgets k\u00f6nnen dann doch ein bisschen mehr. \u00dcber ein Men\u00fc lassen sich die Widgets ausw\u00e4hlen.<\/p>\n<p>Per Rechtsklick sind die Widgets anpassbar. Links, Wettereinstellungen etc. k\u00f6nnen ge\u00e4ndert werden.<\/p>\n<p>Auf den 2. Blick findet man auch einen Editor. Mit dem Editor lassen sich Widgets dann auch selbst erstellen.<br \/>\n<!--more--><br \/>\n<a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/22.jpg\" rel=\"lightbox[1004]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1006\" title=\"22\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/22-300x112.jpg\" alt=\"\" width=\"300\" height=\"112\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/22-300x112.jpg 300w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/22.jpg 842w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Vorgefertigte Widgets gibt es auf der Homepage schon einige. Hier mal eine ganz kleine Auswahl.<\/p>\n<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-1110162011380-L.jpg\" rel=\"lightbox[1004]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-1007\" title=\"1-1110162011380-L\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-1110162011380-L-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> <a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-11101G453500-L.jpg\" rel=\"lightbox[1004]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-1008\" title=\"1-11101G453500-L\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-11101G453500-L-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-11101G453500-L-150x150.jpg 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-11101G453500-L-300x300.jpg 300w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-11101G453500-L.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a> <a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-11101G514450-L.jpg\" rel=\"lightbox[1004]\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-1009 alignnone\" title=\"1-11101G514450-L\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-11101G514450-L-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-11101G514450-L-150x150.jpg 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-11101G514450-L-300x297.jpg 300w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-11101G514450-L.jpg 403w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a> <a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-11101H212340-L.jpg\" rel=\"lightbox[1004]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-1012\" title=\"1-11101H212340-L\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-11101H212340-L-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>Weitere Infos und Download: <a href=\"http:\/\/www.xwidget.com\/index.html\">xwidget.com<\/a><\/p>\n<p>Bilderquelle:xwidget.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Ihr m\u00f6gt \u00a0Anzeigen auf dem Desktop mit Samurize oder Rainmeter? Dann ist XWidget vielleicht auch etwas f\u00fcr euch. \u00a0 XWidget ist f\u00fcr XP, Vista, Windows 7 und auch Windows 8. Auf den ersten Blick sind die Widgets wie wir sie&hellip; <\/p>\n","protected":false},"author":134,"featured_media":1005,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[118,14,9742,117],"class_list":["post-1004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows","tag-gadgets","tag-windows-7-2","tag-windows-8","tag-xwidget"],"wp_featured_image":{"id":1005,"alt_text":"","description":"","media_type":"image","media_details":{"width":"480","height":"456","hwstring_small":"height='96' width='101'","file":"2011\/10\/1-22-2.jpg","sizes":{"thumbnail":{"file":"1-22-2-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-22-2-150x150.jpg"},"medium":{"file":"1-22-2-300x285.jpg","width":"300","height":"285","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-22-2-300x285.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":1004,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-22-2.jpg"},"commentcount":2,"wp_comments":[{"id":271194,"parent":0,"author":5495,"author_name":"pbird","author_email":"pbird.ac@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7d9ee55a0344f123177dd1b609d5b73dc008dcb3ec47d61badf76ee88c0d9c6e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7d9ee55a0344f123177dd1b609d5b73dc008dcb3ec47d61badf76ee88c0d9c6e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7d9ee55a0344f123177dd1b609d5b73dc008dcb3ec47d61badf76ee88c0d9c6e?s=96&d=mm&r=g"},"date":"2024-03-12T10:13:59","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich hatte die XWidgets bis jetzt unter allen Windows-Versionen einschlie\u00dflich der 11 Canary problemlos am laufen. Seit einiger Zeit funktionieren die allerdings nur noch eingeschr\u00e4nkt oder gar nicht, Wetter aktualisiert sich nicht mehr und neue Widgets von der XWidget-Seite werden auch nicht mehr angezeigt wg. &#8222;Verbindungsfehler&#8220;. &#8220; Freunde von mir, einer mit einer standardm\u00e4\u00dfigen W11 und ein anderer noch mit W10, haben das gleiche Problem.<br \/>\nWei\u00df jemand, ob da seitens des Entwicklers noch gewartet wird und ob man damit rechnen kann, da\u00df das irgendwann wieder funktioniert? Oder kennt jemand ein wirklich vergleichbares Tool? Nein, bitte nicht Rainmeter: dessen Widgets sind f\u00fcr PCs und Bildschirmgr\u00f6\u00dfen aus einer anderen Zeit geschrieben und m\u00fcssen daher z. T. stundenlang angepa\u00dft werden, ehe die auf einem 43err Bildschirm so aussehen, wie die das bei XWidget nach einem Klick tun).<\/p>\n"},"status":"1"},{"id":271195,"parent":271194,"author":0,"author_name":"Rush","author_email":"djmajorrush@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=96&d=mm&r=g"},"date":"2024-03-12T10:53:00","cld_nonce":"b6d6726996","content":{"rendered":"<p>was kann XWidgets denn, was andere nicht k\u00f6nnen?<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>XWidget Anzeigen auf dem Desktop - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XWidget Anzeigen auf dem Desktop\" \/>\n<meta property=\"og:description\" content=\"\u00a0Ihr m\u00f6gt \u00a0Anzeigen auf dem Desktop mit Samurize oder Rainmeter? Dann ist XWidget vielleicht auch etwas f\u00fcr euch. \u00a0 XWidget ist f\u00fcr XP, Vista, Windows 7 und auch Windows 8. Auf den ersten Blick sind die Widgets wie wir sie&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-17T14:34:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-14T16:16:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-22-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"456\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2011\\\/10\\\/17\\\/xwidget-anzeigen-auf-dem-desktop\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2011\\\/10\\\/17\\\/xwidget-anzeigen-auf-dem-desktop\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"XWidget Anzeigen auf dem Desktop\",\"datePublished\":\"2011-10-17T14:34:46+00:00\",\"dateModified\":\"2023-01-14T16:16:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2011\\\/10\\\/17\\\/xwidget-anzeigen-auf-dem-desktop\\\/\"},\"wordCount\":124,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2011\\\/10\\\/17\\\/xwidget-anzeigen-auf-dem-desktop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/10\\\/1-22-2.jpg\",\"keywords\":[\"gadgets\",\"windows 7\",\"Windows 8\",\"XWidget\"],\"articleSection\":[\"Windows \u00e4lter\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2011\\\/10\\\/17\\\/xwidget-anzeigen-auf-dem-desktop\\\/#respond\"]}],\"copyrightYear\":\"2011\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2011\\\/10\\\/17\\\/xwidget-anzeigen-auf-dem-desktop\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2011\\\/10\\\/17\\\/xwidget-anzeigen-auf-dem-desktop\\\/\",\"name\":\"XWidget Anzeigen auf dem Desktop - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2011\\\/10\\\/17\\\/xwidget-anzeigen-auf-dem-desktop\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2011\\\/10\\\/17\\\/xwidget-anzeigen-auf-dem-desktop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/10\\\/1-22-2.jpg\",\"datePublished\":\"2011-10-17T14:34:46+00:00\",\"dateModified\":\"2023-01-14T16:16:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2011\\\/10\\\/17\\\/xwidget-anzeigen-auf-dem-desktop\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2011\\\/10\\\/17\\\/xwidget-anzeigen-auf-dem-desktop\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2011\\\/10\\\/17\\\/xwidget-anzeigen-auf-dem-desktop\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/10\\\/1-22-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/10\\\/1-22-2.jpg\",\"width\":\"480\",\"height\":\"456\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2011\\\/10\\\/17\\\/xwidget-anzeigen-auf-dem-desktop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"XWidget Anzeigen auf dem Desktop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"XWidget Anzeigen auf dem Desktop - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/","og_locale":"de_DE","og_type":"article","og_title":"XWidget Anzeigen auf dem Desktop","og_description":"\u00a0Ihr m\u00f6gt \u00a0Anzeigen auf dem Desktop mit Samurize oder Rainmeter? Dann ist XWidget vielleicht auch etwas f\u00fcr euch. \u00a0 XWidget ist f\u00fcr XP, Vista, Windows 7 und auch Windows 8. Auf den ersten Blick sind die Widgets wie wir sie&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2011-10-17T14:34:46+00:00","article_modified_time":"2023-01-14T16:16:20+00:00","og_image":[{"width":480,"height":456,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-22-2.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"XWidget Anzeigen auf dem Desktop","datePublished":"2011-10-17T14:34:46+00:00","dateModified":"2023-01-14T16:16:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/"},"wordCount":124,"commentCount":2,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-22-2.jpg","keywords":["gadgets","windows 7","Windows 8","XWidget"],"articleSection":["Windows \u00e4lter"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/#respond"]}],"copyrightYear":"2011","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/","url":"https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/","name":"XWidget Anzeigen auf dem Desktop - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-22-2.jpg","datePublished":"2011-10-17T14:34:46+00:00","dateModified":"2023-01-14T16:16:20+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-22-2.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-22-2.jpg","width":"480","height":"456"},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2011\/10\/17\/xwidget-anzeigen-auf-dem-desktop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"XWidget Anzeigen auf dem Desktop"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2011\/10\/1-22-2.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/1004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=1004"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/1004\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/1005"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=1004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=1004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=1004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}